{"id":45496,"date":"2026-04-27T13:38:32","date_gmt":"2026-04-27T11:38:32","guid":{"rendered":"http:\/\/localhost:8080\/Paperdux\/index.php\/producto\/monitor-hp-fhd-serie-3-pro-238\/"},"modified":"2026-05-05T15:58:29","modified_gmt":"2026-05-05T13:58:29","slug":"monitor-hp-fhd-serie-3-pro-238","status":"publish","type":"product","link":"https:\/\/canalpapeleria.com\/paperdux\/producto\/monitor-hp-fhd-serie-3-pro-238\/","title":{"rendered":"Monitor HP FHD Serie 3 Pro &#8211; 23,8&#8243;"},"content":{"rendered":"<p>Potencia la productividad c\u00f3modamente con este monitor FHD de 23,8 pulgadas que ofrece una pantalla n\u00edtida y lisa, y un dise\u00f1o sencillo. Cuenta con una relaci\u00f3n de contraste mejorada de 3000:1 y una frecuencia de actualizaci\u00f3n de hasta 100 Hz 3 para ofrecer im\u00e1genes n\u00edtidas y movimientos fluidos. Disfruta de desplazamiento fluido, videos realistas y detalles n\u00edtidos con frecuencia de actualizaci\u00f3n de 100 Hz que proporciona movimiento fluido de fotograma a fotograma. Este monitor est\u00e1 listo para conectarse y disfrutar de im\u00e1genes FHD n\u00edtidas con 1 puerto VGA y 1 puerto HDMI 1.4. Medidas: 595 x 124 x 391 mm.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Potencia la productividad c\u00f3modamente con este monitor FHD de 23,8 pulgadas que ofrece una pantalla n\u00edtida y lisa, y un dise\u00f1o sencillo. Cuenta con una relaci\u00f3n de contraste mejorada de 3000:1 y una frecuencia de actualizaci\u00f3n de hasta 100 Hz 3 para ofrecer im\u00e1genes n\u00edtidas y movimientos fluidos. Disfruta de desplazamiento fluido, videos realistas y detalles n\u00edtidos con frecuencia de actualizaci\u00f3n de 100 Hz que proporciona movimiento fluido de fotograma a fotograma. Este monitor est\u00e1 listo para conectarse y disfrutar de im\u00e1genes FHD n\u00edtidas con 1 puerto VGA y 1 puerto HDMI 1.4. Medidas: 595 x 124 x 391 mm.<\/p>\n","protected":false},"featured_media":38272,"comment_status":"open","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"product_brand":[124],"product_cat":[198],"product_tag":[],"class_list":["post-45496","product","type-product","status-publish","has-post-thumbnail","product_brand-hp","product_cat-informtica-y-electrnica","pa_marca-hp","desktop-align-left","tablet-align-left","mobile-align-left","first","instock","shipping-taxable","purchasable","product-type-simple"],"uagb_featured_image_src":{"full":["https:\/\/canalpapeleria.com\/paperdux\/wp-content\/uploads\/sites\/10\/2026\/04\/221002.jpg",768,768,false],"thumbnail":["https:\/\/canalpapeleria.com\/paperdux\/wp-content\/uploads\/sites\/10\/2026\/04\/221002.jpg",150,150,false],"medium":["https:\/\/canalpapeleria.com\/paperdux\/wp-content\/uploads\/sites\/10\/2026\/04\/221002.jpg",300,300,false],"medium_large":["https:\/\/canalpapeleria.com\/paperdux\/wp-content\/uploads\/sites\/10\/2026\/04\/221002.jpg",768,768,false],"large":["https:\/\/canalpapeleria.com\/paperdux\/wp-content\/uploads\/sites\/10\/2026\/04\/221002.jpg",768,768,false],"1536x1536":["https:\/\/canalpapeleria.com\/paperdux\/wp-content\/uploads\/sites\/10\/2026\/04\/221002.jpg",768,768,false],"2048x2048":["https:\/\/canalpapeleria.com\/paperdux\/wp-content\/uploads\/sites\/10\/2026\/04\/221002.jpg",768,768,false],"woocommerce_thumbnail":["https:\/\/canalpapeleria.com\/paperdux\/wp-content\/uploads\/sites\/10\/2026\/04\/221002.jpg",300,300,false],"woocommerce_single":["https:\/\/canalpapeleria.com\/paperdux\/wp-content\/uploads\/sites\/10\/2026\/04\/221002.jpg",600,600,false],"woocommerce_gallery_thumbnail":["https:\/\/canalpapeleria.com\/paperdux\/wp-content\/uploads\/sites\/10\/2026\/04\/221002.jpg",100,100,false]},"uagb_author_info":{"display_name":"paperdux","author_link":"https:\/\/canalpapeleria.com\/paperdux\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Potencia la productividad c\u00f3modamente con este monitor FHD de 23,8 pulgadas que ofrece una pantalla n\u00edtida y lisa, y un dise\u00f1o sencillo. Cuenta con una relaci\u00f3n de contraste mejorada de 3000:1 y una frecuencia de actualizaci\u00f3n de hasta 100 Hz 3 para ofrecer im\u00e1genes n\u00edtidas y movimientos fluidos. Disfruta de desplazamiento fluido, videos realistas y&hellip;","_links":{"self":[{"href":"https:\/\/canalpapeleria.com\/paperdux\/wp-json\/wp\/v2\/product\/45496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canalpapeleria.com\/paperdux\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/canalpapeleria.com\/paperdux\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/canalpapeleria.com\/paperdux\/wp-json\/wp\/v2\/comments?post=45496"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canalpapeleria.com\/paperdux\/wp-json\/wp\/v2\/media\/38272"}],"wp:attachment":[{"href":"https:\/\/canalpapeleria.com\/paperdux\/wp-json\/wp\/v2\/media?parent=45496"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/canalpapeleria.com\/paperdux\/wp-json\/wp\/v2\/product_brand?post=45496"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/canalpapeleria.com\/paperdux\/wp-json\/wp\/v2\/product_cat?post=45496"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/canalpapeleria.com\/paperdux\/wp-json\/wp\/v2\/product_tag?post=45496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}